{"id":98,"count":1,"description":"","link":"https:\/\/maier-kirschner.de\/en\/tag\/horse-day\/","name":"Horse day","slug":"horse-day","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Horse day Archive - Hotel Maier zum Kirschner in Rottach-Egern am Tegernsee<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maier-kirschner.de\/en\/tag\/horse-day\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horse day Archive - Hotel Maier zum Kirschner in Rottach-Egern am Tegernsee\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maier-kirschner.de\/en\/tag\/horse-day\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Maier zum Kirschner in Rottach-Egern am Tegernsee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/maier-kirschner.de\\\/en\\\/tag\\\/horse-day\\\/\",\"url\":\"https:\\\/\\\/maier-kirschner.de\\\/en\\\/tag\\\/horse-day\\\/\",\"name\":\"Horse day Archive - Hotel Maier zum Kirschner in Rottach-Egern am Tegernsee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maier-kirschner.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maier-kirschner.de\\\/en\\\/tag\\\/horse-day\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maier-kirschner.de\\\/en\\\/tag\\\/horse-day\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/maier-kirschner.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Horse day\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maier-kirschner.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/maier-kirschner.de\\\/en\\\/\",\"name\":\"Maier zum Kirschner\",\"description\":\"Hotel und Restaurant in Rottach-Egern am Tegernsee\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maier-kirschner.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Horse day Archive - Hotel Maier zum Kirschner in Rottach-Egern am Tegernsee","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maier-kirschner.de\/en\/tag\/horse-day\/","og_locale":"en_US","og_type":"article","og_title":"Horse day Archive - Hotel Maier zum Kirschner in Rottach-Egern am Tegernsee","og_url":"https:\/\/maier-kirschner.de\/en\/tag\/horse-day\/","og_site_name":"Hotel Maier zum Kirschner in Rottach-Egern am Tegernsee","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/maier-kirschner.de\/en\/tag\/horse-day\/","url":"https:\/\/maier-kirschner.de\/en\/tag\/horse-day\/","name":"Horse day Archive - Hotel Maier zum Kirschner in Rottach-Egern am Tegernsee","isPartOf":{"@id":"https:\/\/maier-kirschner.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/maier-kirschner.de\/en\/tag\/horse-day\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/maier-kirschner.de\/en\/tag\/horse-day\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/maier-kirschner.de\/en\/"},{"@type":"ListItem","position":2,"name":"Horse day"}]},{"@type":"WebSite","@id":"https:\/\/maier-kirschner.de\/en\/#website","url":"https:\/\/maier-kirschner.de\/en\/","name":"Maier zum Kirschner","description":"Hotel und Restaurant in Rottach-Egern am Tegernsee","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maier-kirschner.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/maier-kirschner.de\/en\/wp-json\/wp\/v2\/tags\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maier-kirschner.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/maier-kirschner.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/maier-kirschner.de\/en\/wp-json\/wp\/v2\/posts?tags=98"},{"href":"https:\/\/maier-kirschner.de\/en\/wp-json\/wp\/v2\/tribe_events?tags=98"},{"href":"https:\/\/maier-kirschner.de\/en\/wp-json\/wp\/v2\/portfolio?tags=98"},{"href":"https:\/\/maier-kirschner.de\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}